{"id":18243,"date":"2022-06-24T07:00:45","date_gmt":"2022-06-24T07:00:45","guid":{"rendered":"https:\/\/kpn.publicita.org\/?p=18180"},"modified":"2022-06-24T07:00:45","modified_gmt":"2022-06-24T07:00:45","slug":"sistemas-fotovoltaicos-tipos","status":"publish","type":"post","link":"https:\/\/kpnenergy.cl\/index.php\/2022\/06\/24\/sistemas-fotovoltaicos-tipos\/","title":{"rendered":"Sistemas fotovoltaicos: tipos y caracter\u00edsticas"},"content":{"rendered":"<p><span style=\"color: #000000;\">La tecnolog\u00eda actual est\u00e1 enfocando sus esfuerzos en ser m\u00e1s \u201cecol\u00f3gica\u201d y respetuosa del ambiente.\u00a0<strong>Los sistemas fotovoltaicos<\/strong>\u00a0entran a esta carrera ofreciendo el aprovechamiento de la energ\u00eda solar de una manera sustentable.<\/span><\/p>\n<h2><span style=\"color: #000000;\">Tipos de sistemas fotovoltaicos<\/span><\/h2>\n<p><span style=\"color: #000000;\"><strong>Los sistemas solares fotovoltaicos<\/strong>\u00a0se consideran como tecnolog\u00eda de energ\u00eda renovable, convirtiendo energ\u00eda solar en electricidad. La manera en que se conecta o no a una red el\u00e9ctrica es la base para clasificar estos sistemas.<\/span><\/p>\n<p><span style=\"color: #000000;\">Existen tres tipos de sistemas, clasificados por la manera como se conectan a la red.\u00a0<b>La <a style=\"color: #000000;\" href=\"http:\/\/kpnenergy.cl\/energia-fotovoltaica\/\" target=\"_blank\" rel=\"noopener\">energ\u00eda fotovoltaica<\/a><\/b>, aprovechada por estos sistemas, puede ser la misma. Lo que los diferencia es la forma de conexi\u00f3n.<\/span><\/p>\n<ul>\n<li><span style=\"color: #000000;\"><strong>Sistemas conectados a red:<\/strong>\u00a0Tambi\u00e9n conocidos como \u201c<strong>sistemas on grid<\/strong>\u201d. Como su nombre indica, estos sistemas est\u00e1n conectados a la red p\u00fablica de corriente alterna.<\/span><\/li>\n<li><span style=\"color: #000000;\"><strong>Sistemas aislados:\u00a0<\/strong>Tambi\u00e9n son conocidos como \u201c<strong>sistemas off grid<\/strong>\u201d. Son sistemas que no se conectan a la red p\u00fablica y que pueden generar por s\u00ed solos la energ\u00eda el\u00e9ctrica necesaria para su funcionamiento.<\/span><\/li>\n<li><span style=\"color: #000000;\"><strong>Sistemas h\u00edbridos:\u00a0<\/strong>Son aquellos que combinan varias fuentes de energ\u00eda, que pueden ser desde generadores a di\u00e9sel hasta configuraciones e\u00f3licas o geot\u00e9rmicas, e incluso la misma red p\u00fablica.<\/span><\/li>\n<\/ul>\n<p><span style=\"color: #000000;\">Veamos las caracter\u00edsticas principales de cada una de ellas.<\/span><\/p>\n<h3><span style=\"color: #000000;\">1. Sistemas conectados a red<\/span><\/h3>\n<p><span style=\"color: #000000;\">La caracter\u00edstica principal de este sistema es su capacidad para conectarse a la red p\u00fablica de energ\u00eda el\u00e9ctrica, pudiendo incluso entregar energ\u00eda a dicha red, si as\u00ed se requiere.<\/span><\/p>\n<h3><span style=\"color: #000000;\">Funciona de la siguiente manera:<\/span><\/h3>\n<p><span style=\"color: #000000;\">La energ\u00eda solar recibida por\u00a0<strong>los paneles solares fotovoltaicos<\/strong>\u00a0es convertida en energ\u00eda el\u00e9ctrica continua (CC). Esta energ\u00eda pasa por el convertidor, que se encarga de transformar esta corriente continua (CC) en corriente alterna (CA).<\/span><\/p>\n<p><span style=\"color: #000000;\">Esta conversi\u00f3n a corriente alterna debe hacerse a la misma frecuencia de la red p\u00fablica para poder conectarse a ella. El convertidor garantiza la calidad del voltaje generado para que sea recibida por la red p\u00fablica.<\/span><\/p>\n<p><span style=\"color: #000000;\">Estos sistemas, por lo general, no tienen bater\u00edas, as\u00ed que su configuraci\u00f3n es la m\u00e1s barata. Son los m\u00e1s utilizados en zonas urbanas, donde hay acceso a la red de energ\u00eda el\u00e9ctrica.<\/span><\/p>\n<blockquote><p>Te puede interesar: <a href=\"http:\/\/kpnenergy.cl\/energia-fotovoltaica-como-produce\/\">Beneficios de la energ\u00eda fotovoltaica en Chile<\/a><\/p><\/blockquote>\n<h3><span style=\"color: #000000;\">2. Sistemas aislados<\/span><\/h3>\n<p><span style=\"color: #000000;\"><strong>Los sistemas off grid<\/strong>\u00a0son aut\u00f3nomos y no est\u00e1n conectados a red alguna u otra fuente de energ\u00eda.<\/span><\/p>\n<p><span style=\"color: #000000;\">Estos sistemas funcionan de la misma manera que los on grid, con<strong>\u00a0<a style=\"color: #000000;\" href=\"https:\/\/www.bbva.com\/es\/sostenibilidad\/que-son-los-paneles-solares-como-funcionan-y-cual-es-su-futuro\/\" target=\"_blank\" rel=\"noopener\">paneles fotovoltaicos<\/a><\/strong>\u00a0recibiendo energ\u00eda solar, convirti\u00e9ndola en corriente continua y pas\u00e1ndola a un conversor que la transforma en energ\u00eda alterna.<\/span><\/p>\n<p><span style=\"color: #000000;\">Pero tienen adicionalmente un banco de bater\u00edas en la que pueden \u201cguardar\u201d energ\u00eda para su consumo posterior, ubicado antes del convertidor. As\u00ed, garantizan energ\u00eda para la casa en d\u00edas soleados, d\u00edas nublados e incluso de noche.<\/span><\/p>\n<p><span style=\"color: #000000;\">Esta configuraci\u00f3n es mucho m\u00e1s costosa que la on grid, sobre todo por el costo de las bater\u00edas. Se aprovecha principalmente en \u00e1reas remotas donde el acceso a la red de energ\u00eda el\u00e9ctrica es escaso o inexistente.<\/span><\/p>\n<h3><span style=\"color: #000000;\">3. Sistemas h\u00edbridos<\/span><\/h3>\n<p><span style=\"color: #000000;\"><strong>El sistema h\u00edbrido<\/strong>\u00a0se integra eficientemente con otras fuentes de energ\u00eda, que puede ser la misma red el\u00e9ctrica, un generador di\u00e9sel, un sistema geot\u00e9rmico, etc\u00e9tera.<\/span><\/p>\n<p><span style=\"color: #000000;\">Su principal diferencia con el sistema on grid es que el convertidor del sistema tambi\u00e9n cumple funciones de cargador para las bater\u00edas, aprovechando la energ\u00eda excedente de los otros sistemas para carga.<\/span><\/p>\n<p><span style=\"color: #000000;\">Esto se da porque es capaz de convertir de CC a CA, como el convertidor del sistema on grid, as\u00ed como de CA a CC para poder realizar las cargas de las bater\u00edas. Estos sistemas tambi\u00e9n son capaces de ofrecer energ\u00eda a la red el\u00e9ctrica p\u00fablica, si est\u00e1n conectados.<\/span><\/p>\n<p><span style=\"color: #000000;\">En conclusi\u00f3n,\u00a0<strong>los sistemas solares fotovoltaicos<\/strong>\u00a0son una soluci\u00f3n muy prometedora a la crisis energ\u00e9tica a la que nos enfrentamos. En\u00a0<strong>KPN Energy <\/strong><strong>Solutions\u00a0<\/strong>sabemos eso y por ello te ofrecemos las mejores soluciones energ\u00e9ticas disponibles en el mercado.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La tecnolog\u00eda actual est\u00e1 enfocando sus esfuerzos en ser m\u00e1s \u201cecol\u00f3gica\u201d y respetuosa del ambiente.\u00a0Los sistemas fotovoltaicos\u00a0entran a esta carrera ofreciendo el aprovechamiento de la energ\u00eda solar de una manera sustentable. Tipos de sistemas fotovoltaicos Los sistemas solares fotovoltaicos\u00a0se consideran como tecnolog\u00eda de energ\u00eda renovable, convirtiendo energ\u00eda solar en electricidad. La manera en que se [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":18244,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41],"tags":[],"class_list":["post-18243","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-energia-fotovoltaica"],"_links":{"self":[{"href":"https:\/\/kpnenergy.cl\/index.php\/wp-json\/wp\/v2\/posts\/18243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kpnenergy.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kpnenergy.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kpnenergy.cl\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/kpnenergy.cl\/index.php\/wp-json\/wp\/v2\/comments?post=18243"}],"version-history":[{"count":0,"href":"https:\/\/kpnenergy.cl\/index.php\/wp-json\/wp\/v2\/posts\/18243\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kpnenergy.cl\/index.php\/wp-json\/wp\/v2\/media\/18244"}],"wp:attachment":[{"href":"https:\/\/kpnenergy.cl\/index.php\/wp-json\/wp\/v2\/media?parent=18243"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kpnenergy.cl\/index.php\/wp-json\/wp\/v2\/categories?post=18243"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kpnenergy.cl\/index.php\/wp-json\/wp\/v2\/tags?post=18243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}